{"id":2428,"date":"2019-09-12T16:00:00","date_gmt":"2019-09-12T14:00:00","guid":{"rendered":"https:\/\/epayspace.com\/?p=2428"},"modified":"2024-06-11T11:52:33","modified_gmt":"2024-06-11T09:52:33","slug":"what-is-open-banking","status":"publish","type":"post","link":"https:\/\/epayspace.com\/fr\/blog\/what-is-open-banking\/","title":{"rendered":"L&rsquo;Open Banking en deux mots"},"content":{"rendered":"\n<div class=\"wp-block-uagb-container uagb-block-4cca6de3 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-323a71a7\"><h1 class=\"uagb-heading-text\"><strong>Open Banking : D\u00e9finition, pourquoi et pour qui ?<\/strong><\/h1><p class=\"uagb-desc-text\">D\u00e9couvrez ce qu&rsquo;est l&rsquo;open banking ou syst\u00e8me bancaire ouvert<\/p><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-0fcd9a9b alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<h2 class=\"wp-block-heading has-ast-global-color-0-color has-text-color has-link-color wp-elements-bb030cc0297907ecd675cb0f8e041d14\"><strong><strong><strong>Qu&rsquo;est-ce que l&rsquo;Open Banking : D\u00e9finition<\/strong><\/strong><\/strong><\/h2>\n\n\n\n<p class=\"has-link-color wp-elements-d931a9a994a647c64dba4b543b77fc88\" style=\"font-size:18px\">Ce nouvel anglicisme qui pourrait \u00eatre traduit par \u00ab\u00a0syst\u00e8me bancaire ouvert\u00a0\u00bb permet aux banques de partager certaines donn\u00e9es de leurs clients \u00e0 d&rsquo;autres acteurs du monde financier sous certaines conditions mais \u00e9galement des donn\u00e9es non personnelles relatives aux banques elles-m\u00eames (ex : emplacements d&rsquo;agences, services fournis etc.). Le principe m\u00eame de syst\u00e8me bancaire ouvert sugg\u00e8re des appr\u00e9hensions tant les notions de s\u00e9curit\u00e9 et de protection assuraient jusqu&rsquo;alors la \u00ab\u00a0garantie\u00a0\u00bb d&rsquo;un argent bien gard\u00e9.<\/p>\n\n\n\n<p class=\"has-link-color wp-elements-ad166c46396f6592dc1f90c1007ba2d6\">En fait, l&rsquo;Open Banking ce n&rsquo;est pas si nouveau. Ce concept est apparu pour la premi\u00e8re fois en 2013 dans la deuxi\u00e8me directive europ\u00e9enne des services de paiements (DSP2) et est devenu une obligation pour les banques depuis janvier 2018. Il promet de nombreuses avanc\u00e9es technologiques dans le secteur financier ce qui est d&rsquo;ailleurs tr\u00e8s favorable \u00e0 l&rsquo;\u00e9mergence des&nbsp;<a href=\"https:\/\/epayspace.com\/fr\/blog\/what-is-fintech\/\">Fintechs<\/a>. En effet, dor\u00e9navant, les donn\u00e9es clients peuvent \u00eatre partag\u00e9es par les banques \u00e0 des tiers dans le but de mieux comprendre les habitudes de consommation (ex : \u00e9pargne etc.). Le partage de ces informations encadr\u00e9 par la loi RGPD, oblige les banques \u00e0 plus de transparence quant \u00e0 l&rsquo;utilisation de ces informations ainsi que sur les transactions commerciales r\u00e9alis\u00e9es avec ces donn\u00e9es, tout en imposant bien s\u00fbr l&rsquo;accord pr\u00e9alable des individus.<\/p>\n\n\n\n<p class=\"has-link-color wp-elements-cf6988161ec539efa2d78a2adbf99904\">L&rsquo;obligation pour les banques de fournir \u00e0 partir de septembre 2019 des connecteurs API (Application Programming Interface) est d&rsquo;ailleurs au c\u0153ur de ce mod\u00e8le. Cette avanc\u00e9e technologique et id\u00e9ologique permet aux d\u00e9veloppeurs tiers de proposer des applications et des services novateurs aux monde de la finance en venant connecter leurs solutions aux bases de donn\u00e9es existantes, cr\u00e9ant de nouvelles interactions et de nouvelles synergies.<\/p>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-f0f13206 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-bbe2c585\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-0b823934\"><h5 class=\"uagb-heading-text\">Vous souhaitez en savoir plus sur nos produits ?<\/h5><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-ccedda06\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-405f2303 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"https:\/\/epayspace.com\/fr\/solutions\/eps-factory\/\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">D\u00e9couvrez EPS Factory<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-69ab9123\">\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1874\" height=\"1840\" src=\"https:\/\/epayspace.com\/wp-content\/uploads\/2024\/06\/Masquotte-EPS-livre.webp\" alt=\"\" class=\"wp-image-4681\" style=\"width:180px\" title=\"Banking as a Service\" srcset=\"https:\/\/epayspace.com\/wp-content\/uploads\/2024\/06\/Masquotte-EPS-livre.webp 1874w, https:\/\/epayspace.com\/wp-content\/uploads\/2024\/06\/Masquotte-EPS-livre-300x295.webp 300w, https:\/\/epayspace.com\/wp-content\/uploads\/2024\/06\/Masquotte-EPS-livre-1024x1005.webp 1024w, https:\/\/epayspace.com\/wp-content\/uploads\/2024\/06\/Masquotte-EPS-livre-768x754.webp 768w, https:\/\/epayspace.com\/wp-content\/uploads\/2024\/06\/Masquotte-EPS-livre-1536x1508.webp 1536w\" sizes=\"auto, (max-width: 1874px) 100vw, 1874px\" \/><\/figure>\n<\/div>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-ast-global-color-0-color has-text-color has-link-color wp-elements-6d6a27c75fa757c326d979d0b8d66fda\"><strong><strong>L&rsquo;Open Banking, mais pourquoi et pour qui ?<\/strong><\/strong><\/h2>\n\n\n\n<p class=\"has-link-color wp-elements-5c86e3c3d705bbd3da285439585b692e\">La digitalisation des services financiers ont pouss\u00e9 les banques \u00e0 d\u00e9velopper toujours plus de nouveaux produits et services en s&rsquo;appuyant sur l&rsquo;explosion des nouvelles technologies et surtout en s&rsquo;appuyant sur l&rsquo;expertise de nouveaux acteurs plus flexibles et plus performants. Cette modernisation soudaine et incontournable invite les \u00e9tablissements bancaires \u00e0 rendre accessibles les donn\u00e9es de leurs clients avec des tiers capables de fournir ces nouveaux services \u00e9volu\u00e9s. Un potentiel de revenus suppl\u00e9mentaire colossal vient donc contre balancer le risque encouru d&rsquo;ouvrir ses portes aux jeunes pousses.<\/p>\n\n\n\n<p class=\"has-link-color wp-elements-b090ecf6de04d3c625c09f7b83004af8\">L&rsquo;ouverture des syst\u00e8mes d&rsquo;information est une v\u00e9ritable r\u00e9volution tant le partage de donn\u00e9es \u00e9tait jusqu&rsquo;ici cloisonn\u00e9 et opaque. Cette ouverture oblige les banques \u00e0 proposer des services extra financiers aussi appel\u00e9s \u00ab\u00a0beyond banking\u00a0\u00bb ; le but \u00e9tant de proposer un service pertinent lorsque le client en a besoin et de se positionner en amont et en aval de ce besoin, de l&rsquo;anticiper et de le satisfaire.<\/p>\n\n\n\n<p class=\"has-link-color wp-elements-dadc0363a7c2ae5328fee510c43c2f71\">La collecte d&rsquo;information coupl\u00e9e \u00e0 la r\u00e9activit\u00e9 des fintechs \u00e0 proposer toujours plus de services innovants \u00e0 leurs clients visent \u00e0 am\u00e9liorer les relations entre le consommateur et sa banque. L&rsquo;exploitation massive des donn\u00e9es collect\u00e9es (Big Data) favorise une meilleure exp\u00e9rience utilisateur et surtout propose des produits et services adapt\u00e9s aux besoins de chacun (ex : placements, investissements, coaching, etc.), la banque personnalis\u00e9e devient encore plus concr\u00e8te.<\/p>\n\n\n\n<p class=\"has-link-color wp-elements-b3539856817032e875742be5857f1478\">Vous l&rsquo;aurez compris, l&rsquo;Open Banking repr\u00e9sente l&rsquo;avenir du secteur bancaire car gr\u00e2ce aux nouvelles technologies et au partage de donn\u00e9es, les acteurs financiers seront capables d&rsquo;anticiper et de proposer de meilleurs services \u00e0 leurs clients.<\/p>\n\n\n\n<p class=\"has-link-color wp-elements-7e37fe82268f70f8828137445a8a9803\">Oui, les r\u00e9ticences des usagers quant \u00e0 la s\u00e9curisation des donn\u00e9es reste l\u00e9gitime, car l&rsquo;Open Banking ouvre aussi le syst\u00e8me \u00e0 de potentiels nouveaux risques de s\u00e9curit\u00e9, de nouvelles failles et surtout de nouvelles tentations. Mais si les nouvelles technologies am\u00e9liorent l&rsquo;exp\u00e9rience client, elles apporteront \u00e9galement et sans aucun doute de nouvelles armes contre la cybercriminalit\u00e9. La loi \u00e9galement de plus en plus attentive \u00e0 l&rsquo;utilisation des donn\u00e9es personnelles sera une arme restrictive sans pr\u00e9c\u00e9dent et le client en restera gagnant. Les nouveaux usages transformeront en profondeur la fa\u00e7on de penser des acteurs traditionnels.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-1d060502 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-7e54697d alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-f170f951 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3bbf16c1\"><h4 class=\"uagb-heading-text\"><strong>Qu\u2019est-ce qu\u2019un Processeur ?<\/strong><\/h4><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-7a084996\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-1377f6f5 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"https:\/\/epayspace.com\/fr\/blog\/what-is-a-processor\/\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Lire l&rsquo;article<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-5eb3dc62 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-09bb1bf0\"><h4 class=\"uagb-heading-text\"><strong>Pourquoi les supports de paiement en closed loop s\u00e9duisent les organisateurs d\u2019\u00e9v\u00e9nements ?<\/strong><\/h4><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-65c16e3a\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-bca1faf8 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"https:\/\/epayspace.com\/fr\/blog\/why-event-organisers-are-attracted-to-closed-loop-payment\/\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Lire l&rsquo;article<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-b2b19c0e alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-8eb53b27\"><h4 class=\"uagb-heading-text\"><strong>Qu\u2019est-ce qu\u2019un BIN Sponsor ?<\/strong><\/h4><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-3dd8ca3d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-18dfdf02 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"https:\/\/epayspace.com\/fr\/blog\/what-is-a-bin-sponsor\/\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Lire l&rsquo;article<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-3ea574e4 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-59a502fa alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-b96ef5da\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-e33eced5\"><h5 class=\"uagb-heading-text\">Besoin d&rsquo;aide pour d\u00e9velopper une solution de paiement ? <\/h5><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-b8c59c7c\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-f6b2cf64 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"https:\/\/epayspace.com\/fr\/solutions\/eps-factory\/contact\/\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Contactez-nous<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-4711ca98\">\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1873\" height=\"1840\" src=\"https:\/\/epayspace.com\/wp-content\/uploads\/2024\/06\/Masquotte-EPS-drapeau.webp\" alt=\"\" class=\"wp-image-4679\" style=\"width:180px\" title=\"Banking as a Service\" srcset=\"https:\/\/epayspace.com\/wp-content\/uploads\/2024\/06\/Masquotte-EPS-drapeau.webp 1873w, https:\/\/epayspace.com\/wp-content\/uploads\/2024\/06\/Masquotte-EPS-drapeau-300x295.webp 300w, https:\/\/epayspace.com\/wp-content\/uploads\/2024\/06\/Masquotte-EPS-drapeau-1024x1006.webp 1024w, https:\/\/epayspace.com\/wp-content\/uploads\/2024\/06\/Masquotte-EPS-drapeau-768x754.webp 768w, https:\/\/epayspace.com\/wp-content\/uploads\/2024\/06\/Masquotte-EPS-drapeau-1536x1509.webp 1536w\" sizes=\"auto, (max-width: 1873px) 100vw, 1873px\" \/><\/figure>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;open banking ou syst\u00e8me bancaire ouvert ? Evolution ou ouverture \u00e0 de nouveaux risques ? D\u00e9couvrez le dans notre blog d\u00e9di\u00e9.<\/p>\n","protected":false},"author":4,"featured_media":4152,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"unboxed","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[18],"tags":[],"class_list":["post-2428","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Open Banking : D\u00e9finition, pourquoi et pour qui ? - E-pay Space, Cr\u00e9ateur de solutions de paiement<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez ce qu&#039;est l&#039;open banking ou syst\u00e8me bancaire ouvert avec E-pay Space, cr\u00e9ateur de solutions de paiements\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/epayspace.com\/fr\/blog\/what-is-open-banking\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Open Banking : D\u00e9finition, pourquoi et pour qui ? - E-pay Space, Cr\u00e9ateur de solutions de paiement\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez ce qu&#039;est l&#039;open banking ou syst\u00e8me bancaire ouvert avec E-pay Space, cr\u00e9ateur de solutions de paiements\" \/>\n<meta property=\"og:url\" content=\"https:\/\/epayspace.com\/fr\/blog\/what-is-open-banking\/\" \/>\n<meta property=\"og:site_name\" content=\"E-pay Space, Cr\u00e9ateur de solutions de paiement\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-12T14:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-11T09:52:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/epayspace.com\/wp-content\/uploads\/2024\/02\/1x11.png\" \/>\n\t<meta property=\"og:image:width\" content=\"377\" \/>\n\t<meta property=\"og:image:height\" content=\"238\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Alexandre Baranger\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alexandre Baranger\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/epayspace.com\/fr\/blog\/what-is-open-banking\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/epayspace.com\/fr\/blog\/what-is-open-banking\/\"},\"author\":{\"name\":\"Alexandre Baranger\",\"@id\":\"https:\/\/epayspace.com\/fr\/#\/schema\/person\/3da6a4736e789ba16e8a9d82985180c3\"},\"headline\":\"L&rsquo;Open Banking en deux mots\",\"datePublished\":\"2019-09-12T14:00:00+00:00\",\"dateModified\":\"2024-06-11T09:52:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/epayspace.com\/fr\/blog\/what-is-open-banking\/\"},\"wordCount\":785,\"publisher\":{\"@id\":\"https:\/\/epayspace.com\/fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/epayspace.com\/fr\/blog\/what-is-open-banking\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/epayspace.com\/wp-content\/uploads\/2024\/02\/1x11.png\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/epayspace.com\/fr\/blog\/what-is-open-banking\/\",\"url\":\"https:\/\/epayspace.com\/fr\/blog\/what-is-open-banking\/\",\"name\":\"Open Banking : D\u00e9finition, pourquoi et pour qui ? - E-pay Space, Cr\u00e9ateur de solutions de paiement\",\"isPartOf\":{\"@id\":\"https:\/\/epayspace.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/epayspace.com\/fr\/blog\/what-is-open-banking\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/epayspace.com\/fr\/blog\/what-is-open-banking\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/epayspace.com\/wp-content\/uploads\/2024\/02\/1x11.png\",\"datePublished\":\"2019-09-12T14:00:00+00:00\",\"dateModified\":\"2024-06-11T09:52:33+00:00\",\"description\":\"D\u00e9couvrez ce qu'est l'open banking ou syst\u00e8me bancaire ouvert avec E-pay Space, cr\u00e9ateur de solutions de paiements\",\"breadcrumb\":{\"@id\":\"https:\/\/epayspace.com\/fr\/blog\/what-is-open-banking\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/epayspace.com\/fr\/blog\/what-is-open-banking\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/epayspace.com\/fr\/blog\/what-is-open-banking\/#primaryimage\",\"url\":\"https:\/\/epayspace.com\/wp-content\/uploads\/2024\/02\/1x11.png\",\"contentUrl\":\"https:\/\/epayspace.com\/wp-content\/uploads\/2024\/02\/1x11.png\",\"width\":377,\"height\":238},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/epayspace.com\/fr\/blog\/what-is-open-banking\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/epayspace.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&rsquo;Open Banking en deux mots\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/epayspace.com\/fr\/#website\",\"url\":\"https:\/\/epayspace.com\/fr\/\",\"name\":\"E-pay Space, Cr\u00e9ateur de solutions de paiement\",\"description\":\"FinTech 100% fran\u00e7aise\",\"publisher\":{\"@id\":\"https:\/\/epayspace.com\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/epayspace.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/epayspace.com\/fr\/#organization\",\"name\":\"E-pay Space\",\"url\":\"https:\/\/epayspace.com\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/epayspace.com\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/epayspace.com\/wp-content\/uploads\/2024\/01\/Logo-1.png\",\"contentUrl\":\"https:\/\/epayspace.com\/wp-content\/uploads\/2024\/01\/Logo-1.png\",\"width\":480,\"height\":240,\"caption\":\"E-pay Space\"},\"image\":{\"@id\":\"https:\/\/epayspace.com\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/epayspace\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/epayspace.com\/fr\/#\/schema\/person\/3da6a4736e789ba16e8a9d82985180c3\",\"name\":\"Alexandre Baranger\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/epayspace.com\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/epayspace.com\/wp-content\/litespeed\/avatar\/757a6a04c25540c9ba8b6fc4a515d49c.jpg?ver=1778649967\",\"contentUrl\":\"https:\/\/epayspace.com\/wp-content\/litespeed\/avatar\/757a6a04c25540c9ba8b6fc4a515d49c.jpg?ver=1778649967\",\"caption\":\"Alexandre Baranger\"},\"sameAs\":[\"https:\/\/mextor.net\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Open Banking : D\u00e9finition, pourquoi et pour qui ? - E-pay Space, Cr\u00e9ateur de solutions de paiement","description":"D\u00e9couvrez ce qu'est l'open banking ou syst\u00e8me bancaire ouvert avec E-pay Space, cr\u00e9ateur de solutions de paiements","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/epayspace.com\/fr\/blog\/what-is-open-banking\/","og_locale":"fr_FR","og_type":"article","og_title":"Open Banking : D\u00e9finition, pourquoi et pour qui ? - E-pay Space, Cr\u00e9ateur de solutions de paiement","og_description":"D\u00e9couvrez ce qu'est l'open banking ou syst\u00e8me bancaire ouvert avec E-pay Space, cr\u00e9ateur de solutions de paiements","og_url":"https:\/\/epayspace.com\/fr\/blog\/what-is-open-banking\/","og_site_name":"E-pay Space, Cr\u00e9ateur de solutions de paiement","article_published_time":"2019-09-12T14:00:00+00:00","article_modified_time":"2024-06-11T09:52:33+00:00","og_image":[{"width":377,"height":238,"url":"https:\/\/epayspace.com\/wp-content\/uploads\/2024\/02\/1x11.png","type":"image\/png"}],"author":"Alexandre Baranger","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Alexandre Baranger","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/epayspace.com\/fr\/blog\/what-is-open-banking\/#article","isPartOf":{"@id":"https:\/\/epayspace.com\/fr\/blog\/what-is-open-banking\/"},"author":{"name":"Alexandre Baranger","@id":"https:\/\/epayspace.com\/fr\/#\/schema\/person\/3da6a4736e789ba16e8a9d82985180c3"},"headline":"L&rsquo;Open Banking en deux mots","datePublished":"2019-09-12T14:00:00+00:00","dateModified":"2024-06-11T09:52:33+00:00","mainEntityOfPage":{"@id":"https:\/\/epayspace.com\/fr\/blog\/what-is-open-banking\/"},"wordCount":785,"publisher":{"@id":"https:\/\/epayspace.com\/fr\/#organization"},"image":{"@id":"https:\/\/epayspace.com\/fr\/blog\/what-is-open-banking\/#primaryimage"},"thumbnailUrl":"https:\/\/epayspace.com\/wp-content\/uploads\/2024\/02\/1x11.png","articleSection":["Blog"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/epayspace.com\/fr\/blog\/what-is-open-banking\/","url":"https:\/\/epayspace.com\/fr\/blog\/what-is-open-banking\/","name":"Open Banking : D\u00e9finition, pourquoi et pour qui ? - E-pay Space, Cr\u00e9ateur de solutions de paiement","isPartOf":{"@id":"https:\/\/epayspace.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/epayspace.com\/fr\/blog\/what-is-open-banking\/#primaryimage"},"image":{"@id":"https:\/\/epayspace.com\/fr\/blog\/what-is-open-banking\/#primaryimage"},"thumbnailUrl":"https:\/\/epayspace.com\/wp-content\/uploads\/2024\/02\/1x11.png","datePublished":"2019-09-12T14:00:00+00:00","dateModified":"2024-06-11T09:52:33+00:00","description":"D\u00e9couvrez ce qu'est l'open banking ou syst\u00e8me bancaire ouvert avec E-pay Space, cr\u00e9ateur de solutions de paiements","breadcrumb":{"@id":"https:\/\/epayspace.com\/fr\/blog\/what-is-open-banking\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/epayspace.com\/fr\/blog\/what-is-open-banking\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/epayspace.com\/fr\/blog\/what-is-open-banking\/#primaryimage","url":"https:\/\/epayspace.com\/wp-content\/uploads\/2024\/02\/1x11.png","contentUrl":"https:\/\/epayspace.com\/wp-content\/uploads\/2024\/02\/1x11.png","width":377,"height":238},{"@type":"BreadcrumbList","@id":"https:\/\/epayspace.com\/fr\/blog\/what-is-open-banking\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/epayspace.com\/fr\/"},{"@type":"ListItem","position":2,"name":"L&rsquo;Open Banking en deux mots"}]},{"@type":"WebSite","@id":"https:\/\/epayspace.com\/fr\/#website","url":"https:\/\/epayspace.com\/fr\/","name":"E-pay Space, Cr\u00e9ateur de solutions de paiement","description":"FinTech 100% fran\u00e7aise","publisher":{"@id":"https:\/\/epayspace.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/epayspace.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/epayspace.com\/fr\/#organization","name":"E-pay Space","url":"https:\/\/epayspace.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/epayspace.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/epayspace.com\/wp-content\/uploads\/2024\/01\/Logo-1.png","contentUrl":"https:\/\/epayspace.com\/wp-content\/uploads\/2024\/01\/Logo-1.png","width":480,"height":240,"caption":"E-pay Space"},"image":{"@id":"https:\/\/epayspace.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/epayspace\/"]},{"@type":"Person","@id":"https:\/\/epayspace.com\/fr\/#\/schema\/person\/3da6a4736e789ba16e8a9d82985180c3","name":"Alexandre Baranger","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/epayspace.com\/fr\/#\/schema\/person\/image\/","url":"https:\/\/epayspace.com\/wp-content\/litespeed\/avatar\/757a6a04c25540c9ba8b6fc4a515d49c.jpg?ver=1778649967","contentUrl":"https:\/\/epayspace.com\/wp-content\/litespeed\/avatar\/757a6a04c25540c9ba8b6fc4a515d49c.jpg?ver=1778649967","caption":"Alexandre Baranger"},"sameAs":["https:\/\/mextor.net"]}]}},"spectra_custom_meta":{"_edit_lock":["1718099557:4"],"_wp_old_date":["2024-01-09","2019-09-01"],"content-type":[""],"_uag_custom_page_level_css":[""],"ast-site-content-layout":["default"],"site-content-style":["unboxed"],"site-post-title":["disabled"],"theme-transparent-header-meta":[""],"adv-header-id-meta":[""],"stick-header-meta":[""],"astra-migrate-meta-layouts":["set"],"footnotes":[""],"_edit_last":["4"],"_yoast_wpseo_primary_category":["18"],"_yoast_wpseo_focuskw":["open banking"],"_yoast_wpseo_metadesc":["D\u00e9couvrez ce qu'est l'open banking ou syst\u00e8me bancaire ouvert avec E-pay Space, cr\u00e9ateur de solutions de paiements"],"_yoast_wpseo_linkdex":["72"],"_yoast_wpseo_content_score":["60"],"_yoast_wpseo_estimated-reading-time-minutes":["5"],"_yoast_wpseo_wordproof_timestamp":[""],"_wpml_word_count":["{\"total\":786,\"to_translate\":{\"en\":61}}"],"_wpml_location_migration_done":["1"],"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"_wp_old_slug":["open-banking"],"_thumbnail_id":["4152"],"_yoast_wpseo_title":["Open Banking : D\u00e9finition, pourquoi et pour qui ? %%sep%% %%sitename%%"],"cmplz_hide_cookiebanner":[""],"_cmplz_scanned_post":["1"],"_uag_css_file_name":["uag-css-2428.css"],"_uag_js_file_name":["uag-js-2428.js"],"_uag_page_assets":["a:9:{s:3:\"css\";s:171913:\".wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}.wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all .3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}.uagb-buttons__outer-wrap .uagb-buttons__wrap{display:inline-flex;width:100%}.uagb-buttons__outer-wrap.uagb-btn__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}@media(max-width: 976px){.uagb-buttons__outer-wrap.uagb-btn-tablet__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn-tablet__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn-tablet__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn-tablet__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}}@media(max-width: 767px){.uagb-buttons__outer-wrap.uagb-btn-mobile__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn-mobile__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn-mobile__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn-mobile__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}}.uagb-buttons__outer-wrap .uagb-buttons-repeater{display:flex;justify-content:center;align-items:center;transition:box-shadow .2s ease}.uagb-buttons__outer-wrap .uagb-buttons-repeater a.uagb-button__link{display:flex;justify-content:center}.uagb-buttons__outer-wrap .uagb-buttons-repeater .uagb-button__icon{font-size:inherit;display:flex;align-items:center}.uagb-buttons__outer-wrap .uagb-buttons-repeater .uagb-button__icon svg{fill:currentColor;width:inherit;height:inherit}.wp-block-uagb-container.uagb-block-4cca6de3 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4cca6de3 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4cca6de3 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4cca6de3 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4cca6de3 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4cca6de3{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4cca6de3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-4cca6de3{box-shadow: 0px 0px   #00000070 ;padding-top: 5%;padding-bottom: 5%;padding-left: 5%;padding-right: 5%;margin-top:  !important;margin-bottom: 0px !important;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 50% 30%;background-size: cover;background-attachment: scroll;background-image: url(https:\/\/epayspace.com\/wp-content\/uploads\/2024\/01\/2dc2ccf6-30e3-4292-a6fa-bc6f71fdc66c.webp);background-clip: padding-box;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-323a71a7.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-7);}.wp-block-uagb-advanced-heading.uagb-block-323a71a7.wp-block-uagb-advanced-heading {text-align: center;margin-top: 0%;margin-right: 0%;margin-bottom: 0%;margin-left: 0%;padding-top: 0%;padding-right: 0%;padding-bottom: 0%;padding-left: 0%;}.wp-block-uagb-advanced-heading.uagb-block-323a71a7.wp-block-uagb-advanced-heading a{color: var(--ast-global-color-3);}.wp-block-uagb-advanced-heading.uagb-block-323a71a7.wp-block-uagb-advanced-heading .uagb-desc-text{color: var(--ast-global-color-7);margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-323a71a7.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-323a71a7.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-323a71a7.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-323a71a7 .uagb-heading-text{font-family: \"Maven Pro\";font-weight: 700;font-size: 30px;margin-bottom: 15px;}.wp-block-uagb-container.uagb-block-0fcd9a9b .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0fcd9a9b .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0fcd9a9b .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0fcd9a9b .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0fcd9a9b .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0fcd9a9b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0fcd9a9b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-0fcd9a9b{box-shadow: 0px 0px   #00000070 ;padding-top: 5%;padding-bottom: 5%;padding-left: 5%;padding-right: 5%;margin-top:  !important;margin-bottom: 0px !important;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-7);;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-f0f13206 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f0f13206 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f0f13206 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f0f13206 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f0f13206 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f0f13206{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f0f13206 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 80%);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 20px;column-gap: 100px;}.wp-block-uagb-container.uagb-block-f0f13206{min-height: 200px;box-shadow: 0px 0px   #00000070 ;padding-top: 1%;padding-bottom: 1%;padding-left: 0%;padding-right: 0%;margin-top: 0% !important;margin-bottom: 0% !important;margin-left: 0%;margin-right: 0%;overflow: visible;order: initial;border-top-left-radius: 40px;border-top-right-radius: 40px;border-bottom-left-radius: 40px;border-bottom-right-radius: 40px;border-color: inherit;background-color: var(--ast-global-color-4);;row-gap: 20px;column-gap: 100px;}.wp-block-uagb-container.uagb-block-bbe2c585 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-bbe2c585 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-bbe2c585 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-bbe2c585 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-bbe2c585 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bbe2c585{max-width: 66%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bbe2c585 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: wrap;align-content: flex-start;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-bbe2c585{min-height: 0px;box-shadow: 0px 0px   #00000070 ;padding-top: 0%;padding-bottom: 0%;padding-left: 0%;padding-right: 0%;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: wrap;align-content: flex-start;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-0b823934.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-0);}.wp-block-uagb-advanced-heading.uagb-block-0b823934.wp-block-uagb-advanced-heading {margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-0b823934.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-0b823934.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0b823934.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0b823934.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0b823934 .uagb-heading-text{font-family: \"Maven Pro\";font-weight: 700;font-size: 25px;}.uagb-block-ccedda06.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-ccedda06.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.wp-block-uagb-buttons .uagb-block-405f2303.wp-block-uagb-buttons-child .uagb-buttons-repeater{background: var(--ast-global-color-2);}.wp-block-uagb-buttons .uagb-block-405f2303 .wp-block-button__link{background: var(--ast-global-color-2);}.wp-block-uagb-buttons .uagb-block-405f2303 .wp-block-button__link:hover{background: var(--ast-global-color-7);}.wp-block-uagb-buttons .uagb-block-405f2303 .wp-block-button__link:focus{background: var(--ast-global-color-7);}.wp-block-uagb-buttons .uagb-block-405f2303 .uagb-button__wrapper .uagb-buttons-repeater{font-family: \"Roboto\";font-weight: 700;text-transform: none;font-size: 18px;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;color: var(--ast-global-color-7);margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}.wp-block-uagb-buttons .uagb-block-405f2303 .wp-block-button__link.has-text-color:hover .uagb-button__link{color: var(--ast-global-color-2);}.wp-block-uagb-buttons .uagb-block-405f2303 .wp-block-button__link.has-text-color:focus .uagb-button__link{color: var(--ast-global-color-2);}.wp-block-uagb-buttons .uagb-block-405f2303 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-405f2303 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-405f2303 .uagb-buttons-repeater.wp-block-button__link{border-top-width: 2px;border-left-width: 2px;border-right-width: 2px;border-bottom-width: 2px;border-top-left-radius: 8px;border-top-right-radius: 8px;border-bottom-left-radius: 8px;border-bottom-right-radius: 8px;border-color: var(--ast-global-color-2);border-style: solid;}.wp-block-uagb-buttons .uagb-block-405f2303 .uagb-buttons-repeater.wp-block-button__link:hover{border-color: var(--ast-global-color-2);}.wp-block-uagb-buttons .uagb-block-405f2303 .uagb-buttons-repeater.wp-block-button__link:focus{border-color: var(--ast-global-color-2);}.wp-block-uagb-buttons .uagb-block-405f2303.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-top-width: 2px;border-left-width: 2px;border-right-width: 2px;border-bottom-width: 2px;border-top-left-radius: 8px;border-top-right-radius: 8px;border-bottom-left-radius: 8px;border-bottom-right-radius: 8px;border-color: var(--ast-global-color-2);border-style: solid;}.wp-block-uagb-buttons .uagb-block-405f2303.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater:hover{border-color: var(--ast-global-color-2);}.wp-block-uagb-buttons .uagb-block-405f2303 .uagb-buttons-repeater .uagb-button__link{color: var(--ast-global-color-7);font-family: \"Roboto\";font-weight: 700;text-transform: none;font-size: 18px;}.wp-block-uagb-buttons .uagb-block-405f2303 .uagb-buttons-repeater:hover .uagb-button__link{color: var(--ast-global-color-2);}.wp-block-uagb-buttons .uagb-block-405f2303 .uagb-buttons-repeater:focus .uagb-button__link{color: var(--ast-global-color-2);}.wp-block-uagb-buttons .uagb-block-405f2303 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: var(--ast-global-color-7);}.wp-block-uagb-buttons .uagb-block-405f2303 .uagb-buttons-repeater:hover .uagb-button__icon > svg{fill: var(--ast-global-color-2);}.wp-block-uagb-buttons .uagb-block-405f2303 .uagb-buttons-repeater:focus .uagb-button__icon > svg{fill: var(--ast-global-color-2);}.wp-block-uagb-buttons .uagb-block-405f2303 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-405f2303 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-buttons .uagb-block-405f2303 .uagb-button__link{font-family: \"Roboto\";text-transform: normal;text-decoration: none;font-weight: 700;}.wp-block-uagb-container.uagb-block-69ab9123 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-69ab9123 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-69ab9123 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-69ab9123 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-69ab9123 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-69ab9123{max-width: 35%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-69ab9123 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-69ab9123{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-1d060502 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1d060502 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1d060502 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1d060502 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1d060502 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1d060502{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1d060502 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-1d060502{box-shadow: 0px 0px   #00000070 ;padding-top: 2%;padding-bottom: 2%;padding-left: 2%;padding-right: 2%;margin-top:  !important;margin-bottom: 0px !important;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-4);;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-7e54697d .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7e54697d .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7e54697d .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7e54697d .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7e54697d .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7e54697d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7e54697d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 4%;}.wp-block-uagb-container.uagb-block-7e54697d{box-shadow: 0px 0px   #00000070 ;padding-top: 0%;padding-bottom: 0%;padding-left: 5%;padding-right: 5%;margin-top: 0% !important;margin-bottom: 0% !important;margin-left: 0%;margin-right: 0%;overflow: visible;order: initial;border-color: inherit;background-color: ;;row-gap: 0px;column-gap: 4%;}.wp-block-uagb-container.uagb-block-f170f951 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f170f951 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f170f951 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f170f951 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f170f951 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f170f951{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f170f951 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 80%);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-f170f951{box-shadow: 0px 2px 5px -1px #00000070 ;padding-top: 5%;padding-bottom: 5%;padding-left: 0%;padding-right: 0%;margin-top: 0% !important;margin-bottom: 0% !important;margin-left: 0%;margin-right: 0%;overflow: visible;order: initial;border-top-left-radius: 20px;border-top-right-radius: 20px;border-bottom-left-radius: 20px;border-bottom-right-radius: 20px;border-color: inherit;background-color: var(--ast-global-color-7);;row-gap: 0px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-3bbf16c1.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-1);}.wp-block-uagb-advanced-heading.uagb-block-3bbf16c1.wp-block-uagb-advanced-heading {text-align: center;margin-top: 0%;margin-right: 0%;margin-bottom: 10%;margin-left: 0%;}.wp-block-uagb-advanced-heading.uagb-block-3bbf16c1.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-3bbf16c1.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-3bbf16c1.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-3bbf16c1.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-3bbf16c1 .uagb-heading-text{font-family: \"Maven Pro\";font-size: 20px;}.uagb-block-7a084996.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-7a084996.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.wp-block-uagb-buttons .uagb-block-1377f6f5.wp-block-uagb-buttons-child .uagb-buttons-repeater{background: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-1377f6f5 .wp-block-button__link{background: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-1377f6f5 .wp-block-button__link:hover{background: var(--ast-global-color-7);}.wp-block-uagb-buttons .uagb-block-1377f6f5 .wp-block-button__link:focus{background: var(--ast-global-color-7);}.wp-block-uagb-buttons .uagb-block-1377f6f5 .uagb-button__wrapper .uagb-buttons-repeater{font-family: \"Roboto\";font-weight: 700;text-transform: none;font-size: 18px;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;color: var(--ast-global-color-7);margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}.wp-block-uagb-buttons .uagb-block-1377f6f5 .wp-block-button__link.has-text-color:hover .uagb-button__link{color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-1377f6f5 .wp-block-button__link.has-text-color:focus .uagb-button__link{color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-1377f6f5 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-1377f6f5 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-1377f6f5 .uagb-buttons-repeater.wp-block-button__link{border-top-width: 2px;border-left-width: 2px;border-right-width: 2px;border-bottom-width: 2px;border-top-left-radius: 8px;border-top-right-radius: 8px;border-bottom-left-radius: 8px;border-bottom-right-radius: 8px;border-color: var(--ast-global-color-1);border-style: solid;}.wp-block-uagb-buttons .uagb-block-1377f6f5 .uagb-buttons-repeater.wp-block-button__link:hover{border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-1377f6f5 .uagb-buttons-repeater.wp-block-button__link:focus{border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-1377f6f5.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-top-width: 2px;border-left-width: 2px;border-right-width: 2px;border-bottom-width: 2px;border-top-left-radius: 8px;border-top-right-radius: 8px;border-bottom-left-radius: 8px;border-bottom-right-radius: 8px;border-color: var(--ast-global-color-1);border-style: solid;}.wp-block-uagb-buttons .uagb-block-1377f6f5.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater:hover{border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-1377f6f5 .uagb-buttons-repeater .uagb-button__link{color: var(--ast-global-color-7);font-family: \"Roboto\";font-weight: 700;text-transform: none;font-size: 18px;}.wp-block-uagb-buttons .uagb-block-1377f6f5 .uagb-buttons-repeater:hover .uagb-button__link{color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-1377f6f5 .uagb-buttons-repeater:focus .uagb-button__link{color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-1377f6f5 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: var(--ast-global-color-7);}.wp-block-uagb-buttons .uagb-block-1377f6f5 .uagb-buttons-repeater:hover .uagb-button__icon > svg{fill: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-1377f6f5 .uagb-buttons-repeater:focus .uagb-button__icon > svg{fill: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-1377f6f5 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-1377f6f5 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-buttons .uagb-block-1377f6f5 .uagb-button__link{font-family: \"Roboto\";text-transform: normal;text-decoration: none;font-weight: 700;}.wp-block-uagb-container.uagb-block-5eb3dc62 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5eb3dc62 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5eb3dc62 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5eb3dc62 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5eb3dc62 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5eb3dc62{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5eb3dc62 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 80%);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-5eb3dc62{box-shadow: 0px 2px 5px -1px #00000070 ;padding-top: 5%;padding-bottom: 5%;padding-left: 0%;padding-right: 0%;margin-top: 0% !important;margin-bottom: 0% !important;margin-left: 0%;margin-right: 0%;overflow: visible;order: initial;border-top-left-radius: 20px;border-top-right-radius: 20px;border-bottom-left-radius: 20px;border-bottom-right-radius: 20px;border-color: inherit;background-color: var(--ast-global-color-7);;row-gap: 0px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-09bb1bf0.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-1);}.wp-block-uagb-advanced-heading.uagb-block-09bb1bf0.wp-block-uagb-advanced-heading {text-align: center;margin-top: 0%;margin-right: 0%;margin-bottom: 10%;margin-left: 0%;}.wp-block-uagb-advanced-heading.uagb-block-09bb1bf0.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-09bb1bf0.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-09bb1bf0.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-09bb1bf0.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-09bb1bf0 .uagb-heading-text{font-family: \"Maven Pro\";font-size: 20px;}.uagb-block-65c16e3a.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-65c16e3a.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.wp-block-uagb-buttons .uagb-block-bca1faf8.wp-block-uagb-buttons-child .uagb-buttons-repeater{background: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-bca1faf8 .wp-block-button__link{background: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-bca1faf8 .wp-block-button__link:hover{background: var(--ast-global-color-7);}.wp-block-uagb-buttons .uagb-block-bca1faf8 .wp-block-button__link:focus{background: var(--ast-global-color-7);}.wp-block-uagb-buttons .uagb-block-bca1faf8 .uagb-button__wrapper .uagb-buttons-repeater{font-family: \"Roboto\";font-weight: 700;text-transform: none;font-size: 18px;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;color: var(--ast-global-color-7);margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}.wp-block-uagb-buttons .uagb-block-bca1faf8 .wp-block-button__link.has-text-color:hover .uagb-button__link{color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-bca1faf8 .wp-block-button__link.has-text-color:focus .uagb-button__link{color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-bca1faf8 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-bca1faf8 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-bca1faf8 .uagb-buttons-repeater.wp-block-button__link{border-top-width: 2px;border-left-width: 2px;border-right-width: 2px;border-bottom-width: 2px;border-top-left-radius: 8px;border-top-right-radius: 8px;border-bottom-left-radius: 8px;border-bottom-right-radius: 8px;border-color: var(--ast-global-color-1);border-style: solid;}.wp-block-uagb-buttons .uagb-block-bca1faf8 .uagb-buttons-repeater.wp-block-button__link:hover{border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-bca1faf8 .uagb-buttons-repeater.wp-block-button__link:focus{border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-bca1faf8.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-top-width: 2px;border-left-width: 2px;border-right-width: 2px;border-bottom-width: 2px;border-top-left-radius: 8px;border-top-right-radius: 8px;border-bottom-left-radius: 8px;border-bottom-right-radius: 8px;border-color: var(--ast-global-color-1);border-style: solid;}.wp-block-uagb-buttons .uagb-block-bca1faf8.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater:hover{border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-bca1faf8 .uagb-buttons-repeater .uagb-button__link{color: var(--ast-global-color-7);font-family: \"Roboto\";font-weight: 700;text-transform: none;font-size: 18px;}.wp-block-uagb-buttons .uagb-block-bca1faf8 .uagb-buttons-repeater:hover .uagb-button__link{color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-bca1faf8 .uagb-buttons-repeater:focus .uagb-button__link{color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-bca1faf8 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: var(--ast-global-color-7);}.wp-block-uagb-buttons .uagb-block-bca1faf8 .uagb-buttons-repeater:hover .uagb-button__icon > svg{fill: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-bca1faf8 .uagb-buttons-repeater:focus .uagb-button__icon > svg{fill: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-bca1faf8 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-bca1faf8 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-buttons .uagb-block-bca1faf8 .uagb-button__link{font-family: \"Roboto\";text-transform: normal;text-decoration: none;font-weight: 700;}.wp-block-uagb-container.uagb-block-b2b19c0e .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b2b19c0e .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b2b19c0e .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b2b19c0e .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b2b19c0e .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b2b19c0e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b2b19c0e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 80%);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-b2b19c0e{box-shadow: 0px 2px 5px -1px #00000070 ;padding-top: 5%;padding-bottom: 5%;padding-left: 0%;padding-right: 0%;margin-top: 0% !important;margin-bottom: 0% !important;margin-left: 0%;margin-right: 0%;overflow: visible;order: initial;border-top-left-radius: 20px;border-top-right-radius: 20px;border-bottom-left-radius: 20px;border-bottom-right-radius: 20px;border-color: inherit;background-color: var(--ast-global-color-7);;row-gap: 0px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-8eb53b27.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-1);}.wp-block-uagb-advanced-heading.uagb-block-8eb53b27.wp-block-uagb-advanced-heading {text-align: center;margin-top: 0%;margin-right: 0%;margin-bottom: 10%;margin-left: 0%;}.wp-block-uagb-advanced-heading.uagb-block-8eb53b27.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-8eb53b27.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8eb53b27.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8eb53b27.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8eb53b27 .uagb-heading-text{font-family: \"Maven Pro\";font-size: 20px;}.uagb-block-3dd8ca3d.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-3dd8ca3d.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.wp-block-uagb-buttons .uagb-block-18dfdf02.wp-block-uagb-buttons-child .uagb-buttons-repeater{background: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-18dfdf02 .wp-block-button__link{background: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-18dfdf02 .wp-block-button__link:hover{background: var(--ast-global-color-7);}.wp-block-uagb-buttons .uagb-block-18dfdf02 .wp-block-button__link:focus{background: var(--ast-global-color-7);}.wp-block-uagb-buttons .uagb-block-18dfdf02 .uagb-button__wrapper .uagb-buttons-repeater{font-family: \"Roboto\";font-weight: 700;text-transform: none;font-size: 18px;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;color: var(--ast-global-color-7);margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}.wp-block-uagb-buttons .uagb-block-18dfdf02 .wp-block-button__link.has-text-color:hover .uagb-button__link{color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-18dfdf02 .wp-block-button__link.has-text-color:focus .uagb-button__link{color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-18dfdf02 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-18dfdf02 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-18dfdf02 .uagb-buttons-repeater.wp-block-button__link{border-top-width: 2px;border-left-width: 2px;border-right-width: 2px;border-bottom-width: 2px;border-top-left-radius: 8px;border-top-right-radius: 8px;border-bottom-left-radius: 8px;border-bottom-right-radius: 8px;border-color: var(--ast-global-color-1);border-style: solid;}.wp-block-uagb-buttons .uagb-block-18dfdf02 .uagb-buttons-repeater.wp-block-button__link:hover{border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-18dfdf02 .uagb-buttons-repeater.wp-block-button__link:focus{border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-18dfdf02.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-top-width: 2px;border-left-width: 2px;border-right-width: 2px;border-bottom-width: 2px;border-top-left-radius: 8px;border-top-right-radius: 8px;border-bottom-left-radius: 8px;border-bottom-right-radius: 8px;border-color: var(--ast-global-color-1);border-style: solid;}.wp-block-uagb-buttons .uagb-block-18dfdf02.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater:hover{border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-18dfdf02 .uagb-buttons-repeater .uagb-button__link{color: var(--ast-global-color-7);font-family: \"Roboto\";font-weight: 700;text-transform: none;font-size: 18px;}.wp-block-uagb-buttons .uagb-block-18dfdf02 .uagb-buttons-repeater:hover .uagb-button__link{color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-18dfdf02 .uagb-buttons-repeater:focus .uagb-button__link{color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-18dfdf02 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: var(--ast-global-color-7);}.wp-block-uagb-buttons .uagb-block-18dfdf02 .uagb-buttons-repeater:hover .uagb-button__icon > svg{fill: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-18dfdf02 .uagb-buttons-repeater:focus .uagb-button__icon > svg{fill: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-18dfdf02 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-18dfdf02 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-buttons .uagb-block-18dfdf02 .uagb-button__link{font-family: \"Roboto\";text-transform: normal;text-decoration: none;font-weight: 700;}.wp-block-uagb-container.uagb-block-3ea574e4 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3ea574e4 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3ea574e4 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3ea574e4 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3ea574e4 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3ea574e4{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3ea574e4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-3ea574e4{box-shadow: 0px 0px   #00000070 ;padding-top: 2%;padding-bottom: 2%;padding-left: 5%;padding-right: 5%;margin-top:  !important;margin-bottom: 0px !important;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-7);;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-59a502fa .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-59a502fa .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-59a502fa .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-59a502fa .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-59a502fa .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-59a502fa{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-59a502fa > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 80%);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 20px;column-gap: 100px;}.wp-block-uagb-container.uagb-block-59a502fa{min-height: 200px;box-shadow: 0px 0px   #00000070 ;padding-top: 1%;padding-bottom: 1%;padding-left: 0%;padding-right: 0%;margin-top: 0% !important;margin-bottom: 0% !important;margin-left: 0%;margin-right: 0%;overflow: visible;order: initial;border-top-left-radius: 40px;border-top-right-radius: 40px;border-bottom-left-radius: 40px;border-bottom-right-radius: 40px;border-color: inherit;background-color: var(--ast-global-color-7);;row-gap: 20px;column-gap: 100px;}.wp-block-uagb-container.uagb-block-b96ef5da .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b96ef5da .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b96ef5da .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b96ef5da .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b96ef5da .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b96ef5da{max-width: 66%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b96ef5da > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: wrap;align-content: flex-start;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-b96ef5da{min-height: 0px;box-shadow: 0px 0px   #00000070 ;padding-top: 0%;padding-bottom: 0%;padding-left: 0%;padding-right: 0%;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: wrap;align-content: flex-start;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-e33eced5.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-0);}.wp-block-uagb-advanced-heading.uagb-block-e33eced5.wp-block-uagb-advanced-heading {margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-e33eced5.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-e33eced5.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e33eced5.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e33eced5.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e33eced5 .uagb-heading-text{font-family: \"Maven Pro\";font-weight: 700;font-size: 25px;}.uagb-block-b8c59c7c.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-b8c59c7c.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.wp-block-uagb-buttons .uagb-block-f6b2cf64.wp-block-uagb-buttons-child .uagb-buttons-repeater{background: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-f6b2cf64 .wp-block-button__link{background: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-f6b2cf64 .wp-block-button__link:hover{background: var(--ast-global-color-7);}.wp-block-uagb-buttons .uagb-block-f6b2cf64 .wp-block-button__link:focus{background: var(--ast-global-color-7);}.wp-block-uagb-buttons .uagb-block-f6b2cf64 .uagb-button__wrapper .uagb-buttons-repeater{font-family: \"Roboto\";font-weight: 700;text-transform: none;font-size: 18px;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;color: var(--ast-global-color-7);margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}.wp-block-uagb-buttons .uagb-block-f6b2cf64 .wp-block-button__link.has-text-color:hover .uagb-button__link{color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-f6b2cf64 .wp-block-button__link.has-text-color:focus .uagb-button__link{color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-f6b2cf64 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-f6b2cf64 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-f6b2cf64 .uagb-buttons-repeater.wp-block-button__link{border-top-width: 2px;border-left-width: 2px;border-right-width: 2px;border-bottom-width: 2px;border-top-left-radius: 8px;border-top-right-radius: 8px;border-bottom-left-radius: 8px;border-bottom-right-radius: 8px;border-color: var(--ast-global-color-1);border-style: solid;}.wp-block-uagb-buttons .uagb-block-f6b2cf64 .uagb-buttons-repeater.wp-block-button__link:hover{border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-f6b2cf64 .uagb-buttons-repeater.wp-block-button__link:focus{border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-f6b2cf64.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-top-width: 2px;border-left-width: 2px;border-right-width: 2px;border-bottom-width: 2px;border-top-left-radius: 8px;border-top-right-radius: 8px;border-bottom-left-radius: 8px;border-bottom-right-radius: 8px;border-color: var(--ast-global-color-1);border-style: solid;}.wp-block-uagb-buttons .uagb-block-f6b2cf64.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater:hover{border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-f6b2cf64 .uagb-buttons-repeater .uagb-button__link{color: var(--ast-global-color-7);font-family: \"Roboto\";font-weight: 700;text-transform: none;font-size: 18px;}.wp-block-uagb-buttons .uagb-block-f6b2cf64 .uagb-buttons-repeater:hover .uagb-button__link{color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-f6b2cf64 .uagb-buttons-repeater:focus .uagb-button__link{color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-f6b2cf64 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: var(--ast-global-color-7);}.wp-block-uagb-buttons .uagb-block-f6b2cf64 .uagb-buttons-repeater:hover .uagb-button__icon > svg{fill: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-f6b2cf64 .uagb-buttons-repeater:focus .uagb-button__icon > svg{fill: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-f6b2cf64 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-f6b2cf64 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-buttons .uagb-block-f6b2cf64 .uagb-button__link{font-family: \"Roboto\";text-transform: normal;text-decoration: none;font-weight: 700;}.wp-block-uagb-container.uagb-block-4711ca98 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4711ca98 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4711ca98 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4711ca98 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4711ca98 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4711ca98{max-width: 35%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4711ca98 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-4711ca98{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-4cca6de3{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4cca6de3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-4cca6de3{padding-top: 0%;padding-bottom: 0%;padding-left: 0%;padding-right: 0%;margin-top:  !important;margin-bottom: 0px !important;order: initial;background-image: url(https:\/\/epayspace.com\/wp-content\/uploads\/2024\/01\/2dc2ccf6-30e3-4292-a6fa-bc6f71fdc66c.webp);background-clip: padding-box;}.wp-block-uagb-advanced-heading.uagb-block-323a71a7.wp-block-uagb-advanced-heading {padding-top: 0%;padding-right: 5%;padding-bottom: 0%;padding-left: 5%;margin-top: 5%;margin-right: 0%;margin-bottom: 5%;margin-left: 0%;}.wp-block-uagb-advanced-heading.uagb-block-323a71a7 .uagb-heading-text{font-size: 25px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0fcd9a9b{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0fcd9a9b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-0fcd9a9b{padding-top: 5%;padding-bottom: 5%;padding-left: 5%;padding-right: 5%;margin-top:  !important;margin-bottom: 0px !important;order: initial;background-color: var(--ast-global-color-7);;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f0f13206{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f0f13206 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;column-gap: 80px;}.wp-block-uagb-container.uagb-block-f0f13206{padding-top: 5%;padding-bottom: 5%;padding-left: 5%;padding-right: 5%;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-4);;column-gap: 80px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bbe2c585{max-width: 60%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bbe2c585 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;flex-wrap: wrap;align-content: flex-start;column-gap: 100px;}.wp-block-uagb-container.uagb-block-bbe2c585{padding-top: 0%;padding-bottom: 0%;padding-left: 0%;padding-right: 0%;margin-top:  !important;margin-bottom:  !important;order: initial;flex-direction: column;align-items: flex-start;flex-wrap: wrap;align-content: flex-start;column-gap: 100px;}.wp-block-uagb-container.uagb-block-bbe2c585.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-bbe2c585.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.wp-block-uagb-advanced-heading.uagb-block-0b823934 .uagb-heading-text{font-size: 20px;}.uagb-block-ccedda06.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.uagb-block-ccedda06.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.uagb-block-ccedda06 .uagb-buttons-repeater:not(.wp-block-button__link){padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;}.uagb-block-ccedda06 .uagb-buttons-repeater.wp-block-button__link{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;}.wp-block-uagb-buttons .uagb-block-405f2303.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: var(--ast-global-color-2);}.wp-block-uagb-buttons .uagb-block-405f2303 .uagb-buttons-repeater .uagb-button__link{font-size: 15px;}.wp-block-uagb-buttons .uagb-block-405f2303 .uagb-buttons-repeater.wp-block-button__link{padding-top: 8px;padding-bottom: 8px;padding-left: 8px;padding-right: 8px;border-style: solid;border-color: var(--ast-global-color-2);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-69ab9123{max-width: 40%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-69ab9123 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;}.wp-block-uagb-container.uagb-block-69ab9123{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;align-items: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1d060502{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1d060502 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-1d060502{padding-top: 5%;padding-bottom: 5%;padding-left: 5%;padding-right: 5%;margin-top:  !important;margin-bottom: 0px !important;order: initial;background-color: var(--ast-global-color-4);;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7e54697d{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7e54697d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;column-gap: 6%;}.wp-block-uagb-container.uagb-block-7e54697d{padding-top: 0%;padding-bottom: 0%;padding-left: 0%;padding-right: 0%;margin-top: 0% !important;margin-bottom: 0% !important;margin-left: 0%;margin-right: 0%;order: initial;background-color: ;;column-gap: 6%;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f170f951{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f170f951 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: center;}.wp-block-uagb-container.uagb-block-f170f951{padding-top: 5%;padding-bottom: 5%;padding-left: 2%;padding-right: 2%;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-7);;}.wp-block-uagb-advanced-heading.uagb-block-3bbf16c1 .uagb-heading-text{font-size: 18px;}.uagb-block-7a084996.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-7a084996.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-1377f6f5.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-1377f6f5 .uagb-buttons-repeater .uagb-button__link{font-size: 15px;}.wp-block-uagb-buttons .uagb-block-1377f6f5 .uagb-buttons-repeater.wp-block-button__link{padding-top: 8px;padding-bottom: 8px;padding-left: 8px;padding-right: 8px;border-style: solid;border-color: var(--ast-global-color-1);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5eb3dc62{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5eb3dc62 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: center;}.wp-block-uagb-container.uagb-block-5eb3dc62{padding-top: 5%;padding-bottom: 5%;padding-left: 2%;padding-right: 2%;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-7);;}.wp-block-uagb-advanced-heading.uagb-block-09bb1bf0 .uagb-heading-text{font-size: 18px;}.uagb-block-65c16e3a.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-65c16e3a.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-bca1faf8.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-bca1faf8 .uagb-buttons-repeater .uagb-button__link{font-size: 15px;}.wp-block-uagb-buttons .uagb-block-bca1faf8 .uagb-buttons-repeater.wp-block-button__link{padding-top: 8px;padding-bottom: 8px;padding-left: 8px;padding-right: 8px;border-style: solid;border-color: var(--ast-global-color-1);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b2b19c0e{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b2b19c0e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: center;}.wp-block-uagb-container.uagb-block-b2b19c0e{padding-top: 5%;padding-bottom: 5%;padding-left: 2%;padding-right: 2%;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-7);;}.wp-block-uagb-advanced-heading.uagb-block-8eb53b27 .uagb-heading-text{font-size: 18px;}.uagb-block-3dd8ca3d.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-3dd8ca3d.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-18dfdf02.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-18dfdf02 .uagb-buttons-repeater .uagb-button__link{font-size: 15px;}.wp-block-uagb-buttons .uagb-block-18dfdf02 .uagb-buttons-repeater.wp-block-button__link{padding-top: 8px;padding-bottom: 8px;padding-left: 8px;padding-right: 8px;border-style: solid;border-color: var(--ast-global-color-1);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3ea574e4{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3ea574e4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-3ea574e4{padding-top: 5%;padding-bottom: 5%;padding-left: 5%;padding-right: 5%;margin-top:  !important;margin-bottom: 0px !important;order: initial;background-color: var(--ast-global-color-7);;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-59a502fa{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-59a502fa > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;column-gap: 80px;}.wp-block-uagb-container.uagb-block-59a502fa{padding-top: 5%;padding-bottom: 5%;padding-left: 5%;padding-right: 5%;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-7);;column-gap: 80px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b96ef5da{max-width: 60%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b96ef5da > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;flex-wrap: wrap;align-content: flex-start;column-gap: 100px;}.wp-block-uagb-container.uagb-block-b96ef5da{padding-top: 0%;padding-bottom: 0%;padding-left: 0%;padding-right: 0%;margin-top:  !important;margin-bottom:  !important;order: initial;flex-direction: column;align-items: flex-start;flex-wrap: wrap;align-content: flex-start;column-gap: 100px;}.wp-block-uagb-container.uagb-block-b96ef5da.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-b96ef5da.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.wp-block-uagb-advanced-heading.uagb-block-e33eced5 .uagb-heading-text{font-size: 20px;}.uagb-block-b8c59c7c.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.uagb-block-b8c59c7c.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.uagb-block-b8c59c7c .uagb-buttons-repeater:not(.wp-block-button__link){padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;}.uagb-block-b8c59c7c .uagb-buttons-repeater.wp-block-button__link{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;}.wp-block-uagb-buttons .uagb-block-f6b2cf64.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-f6b2cf64 .uagb-buttons-repeater .uagb-button__link{font-size: 15px;}.wp-block-uagb-buttons .uagb-block-f6b2cf64 .uagb-buttons-repeater.wp-block-button__link{padding-top: 8px;padding-bottom: 8px;padding-left: 8px;padding-right: 8px;border-style: solid;border-color: var(--ast-global-color-1);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4711ca98{max-width: 40%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4711ca98 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;}.wp-block-uagb-container.uagb-block-4711ca98{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;align-items: stretch;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-4cca6de3{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4cca6de3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-4cca6de3{padding-top: 5%;padding-bottom: 5%;padding-left: 5%;padding-right: 5%;margin-top:  !important;margin-bottom: 0px !important;order: initial;background-image: url(https:\/\/epayspace.com\/wp-content\/uploads\/2024\/01\/2dc2ccf6-30e3-4292-a6fa-bc6f71fdc66c.webp);background-clip: padding-box;}.wp-block-uagb-advanced-heading.uagb-block-323a71a7.wp-block-uagb-advanced-heading {padding-top: 0%;padding-right: 5%;padding-bottom: 0%;padding-left: 5%;margin-top: 5%;margin-right: 0%;margin-bottom: 0%;margin-left: 0%;}.wp-block-uagb-advanced-heading.uagb-block-323a71a7 .uagb-heading-text{font-size: 25px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0fcd9a9b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0fcd9a9b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: flex-start;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-0fcd9a9b{padding-top: 10%;padding-bottom: 10%;padding-left: 10%;padding-right: 10%;margin-top:  !important;margin-bottom: 0px !important;order: initial;background-color: var(--ast-global-color-7);;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f0f13206{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f0f13206 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-f0f13206{padding-top: 5%;padding-bottom: 5%;padding-left: 5%;padding-right: 5%;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-4);;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bbe2c585{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bbe2c585 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;flex-wrap: wrap;align-content: flex-start;}.wp-block-uagb-container.uagb-block-bbe2c585{padding-top: 10%;padding-bottom: 10%;padding-left: 8%;padding-right: 8%;margin-top:  !important;margin-bottom:  !important;order: initial;flex-direction: column;align-items: flex-start;flex-wrap: wrap;align-content: flex-start;}.wp-block-uagb-container.uagb-block-bbe2c585.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-bbe2c585.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.wp-block-uagb-advanced-heading.uagb-block-0b823934 .uagb-heading-text{font-size: 20px;}.uagb-block-ccedda06.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.uagb-block-ccedda06.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-405f2303.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: var(--ast-global-color-2);}.wp-block-uagb-buttons .uagb-block-405f2303 .uagb-buttons-repeater .uagb-button__link{font-size: 15px;}.wp-block-uagb-buttons .uagb-block-405f2303 .uagb-buttons-repeater.wp-block-button__link{padding-top: 6px;padding-bottom: 6px;padding-left: 6px;padding-right: 6px;border-style: solid;border-color: var(--ast-global-color-2);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-69ab9123{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-69ab9123 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-69ab9123{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;align-items: stretch;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1d060502{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1d060502 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-1d060502{padding-top: 0%;padding-bottom: 0%;padding-left: 0%;padding-right: 0%;margin-top:  !important;margin-bottom: 0px !important;order: initial;background-color: var(--ast-global-color-4);;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7e54697d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7e54697d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: wrap;align-content: center;row-gap: 15px;}.wp-block-uagb-container.uagb-block-7e54697d{padding-top: 10%;padding-bottom: 10%;padding-left: 5%;padding-right: 5%;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 15px;order: initial;background-color: ;;}.wp-block-uagb-container.uagb-block-7e54697d.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-7e54697d.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f170f951{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f170f951 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: center;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-f170f951{padding-top: 10%;padding-bottom: 10%;padding-left: 10%;padding-right: 10%;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-7);;}.uagb-block-7a084996.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-7a084996.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-1377f6f5.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-1377f6f5 .uagb-buttons-repeater .uagb-button__link{font-size: 15px;}.wp-block-uagb-buttons .uagb-block-1377f6f5 .uagb-buttons-repeater.wp-block-button__link{padding-top: 6px;padding-bottom: 6px;padding-left: 6px;padding-right: 6px;border-style: solid;border-color: var(--ast-global-color-1);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5eb3dc62{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5eb3dc62 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: center;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-5eb3dc62{padding-top: 10%;padding-bottom: 10%;padding-left: 10%;padding-right: 10%;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-7);;}.uagb-block-65c16e3a.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-65c16e3a.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-bca1faf8.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-bca1faf8 .uagb-buttons-repeater .uagb-button__link{font-size: 15px;}.wp-block-uagb-buttons .uagb-block-bca1faf8 .uagb-buttons-repeater.wp-block-button__link{padding-top: 6px;padding-bottom: 6px;padding-left: 6px;padding-right: 6px;border-style: solid;border-color: var(--ast-global-color-1);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b2b19c0e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b2b19c0e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: center;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-b2b19c0e{padding-top: 10%;padding-bottom: 10%;padding-left: 10%;padding-right: 10%;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-7);;}.uagb-block-3dd8ca3d.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-3dd8ca3d.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-18dfdf02.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-18dfdf02 .uagb-buttons-repeater .uagb-button__link{font-size: 15px;}.wp-block-uagb-buttons .uagb-block-18dfdf02 .uagb-buttons-repeater.wp-block-button__link{padding-top: 6px;padding-bottom: 6px;padding-left: 6px;padding-right: 6px;border-style: solid;border-color: var(--ast-global-color-1);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3ea574e4{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3ea574e4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: flex-start;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-3ea574e4{padding-top: 10%;padding-bottom: 10%;padding-left: 10%;padding-right: 10%;margin-top:  !important;margin-bottom: 0px !important;order: initial;background-color: var(--ast-global-color-7);;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-59a502fa{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-59a502fa > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-59a502fa{padding-top: 5%;padding-bottom: 5%;padding-left: 5%;padding-right: 5%;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-7);;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b96ef5da{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b96ef5da > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;flex-wrap: wrap;align-content: flex-start;}.wp-block-uagb-container.uagb-block-b96ef5da{padding-top: 10%;padding-bottom: 10%;padding-left: 8%;padding-right: 8%;margin-top:  !important;margin-bottom:  !important;order: initial;flex-direction: column;align-items: flex-start;flex-wrap: wrap;align-content: flex-start;}.wp-block-uagb-container.uagb-block-b96ef5da.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-b96ef5da.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.wp-block-uagb-advanced-heading.uagb-block-e33eced5 .uagb-heading-text{font-size: 20px;}.uagb-block-b8c59c7c.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.uagb-block-b8c59c7c.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-f6b2cf64.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-f6b2cf64 .uagb-buttons-repeater .uagb-button__link{font-size: 15px;}.wp-block-uagb-buttons .uagb-block-f6b2cf64 .uagb-buttons-repeater.wp-block-button__link{padding-top: 6px;padding-bottom: 6px;padding-left: 6px;padding-right: 6px;border-style: solid;border-color: var(--ast-global-color-1);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4711ca98{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4711ca98 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-4711ca98{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;align-items: stretch;flex-wrap: wrap;}}.uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}.wp-block-uagb-container.uagb-block-a8dbac6d .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a8dbac6d .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a8dbac6d .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a8dbac6d .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a8dbac6d .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a8dbac6d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a8dbac6d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-a8dbac6d{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-b23ff043 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b23ff043 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b23ff043 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b23ff043 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b23ff043 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b23ff043{max-width: 25%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b23ff043 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-b23ff043{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-b2fff4fe.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-b2fff4fe.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-b2fff4fe.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-b2fff4fe.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-e1daa621 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e1daa621 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e1daa621 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e1daa621 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e1daa621 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e1daa621{max-width: 25%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e1daa621 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-e1daa621{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-0b79243b.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-0b79243b.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0b79243b.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0b79243b.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-7af1c425 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7af1c425 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7af1c425 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7af1c425 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7af1c425 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7af1c425{max-width: 25%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7af1c425 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-7af1c425{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-be6527bc.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-be6527bc.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-be6527bc.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-be6527bc.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-a7d959da .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a7d959da .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a7d959da .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a7d959da .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a7d959da .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a7d959da{max-width: 25%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a7d959da > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-a7d959da{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-20d36741.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-20d36741.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-20d36741.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-20d36741.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-a8dbac6d{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a8dbac6d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-a8dbac6d{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b23ff043{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b23ff043 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-b23ff043{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e1daa621{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e1daa621 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-e1daa621{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7af1c425{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7af1c425 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-7af1c425{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a7d959da{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a7d959da > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-a7d959da{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-a8dbac6d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a8dbac6d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-a8dbac6d{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b23ff043{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b23ff043 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-b23ff043{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e1daa621{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e1daa621 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-e1daa621{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7af1c425{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7af1c425 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-7af1c425{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a7d959da{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a7d959da > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-a7d959da{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}}.uagb-social-share__outer-wrap,.uagb-social-share__wrap{display:flex;align-items:center;justify-content:center}.uagb-social-share__layout-vertical.uagb-social-share__outer-wrap,.uagb-social-share__layout-vertical .uagb-social-share__wrap{flex-direction:column}.uagb-social-share__layout-vertical .wp-block-uagb-social-share-child.uagb-ss-repeater.uagb-ss__wrapper:first-child{margin-top:0 !important}.uagb-social-share__layout-vertical .wp-block-uagb-social-share-child.uagb-ss-repeater.uagb-ss__wrapper:last-child{margin-bottom:0 !important}.uagb-social-share__outer-wrap a.uagb-button__link:focus{box-shadow:none}.uagb-social-share__outer-wrap .uagb-ss__wrapper{padding:0;margin-left:5px;margin-right:5px;transition:all .2s;display:inline-flex;text-align:center}.uagb-social-share__outer-wrap .uagb-ss__source-wrap{display:inline-block}.uagb-social-share__outer-wrap .uagb-ss__link{color:#3a3a3a;display:inline-table;line-height:0;cursor:pointer}.uagb-social-share__outer-wrap .uagb-ss__source-icon{font-size:40px;width:40px;height:40px}.uagb-social-share__outer-wrap .uagb-ss__source-image{width:40px}@media(max-width: 976px){.uagb-social-share__layout-horizontal .uagb-ss__wrapper{margin-left:0;margin-right:0}}.uagb-social-share__layout-horizontal .wp-block-uagb-social-share-child.uagb-ss-repeater.uagb-ss__wrapper:first-child{margin-left:0 !important}.uagb-social-share__layout-horizontal .wp-block-uagb-social-share-child.uagb-ss-repeater.uagb-ss__wrapper:last-child{margin-right:0 !important}.wp-block-uagb-social-share .uagb-social-share__wrapper{text-decoration:none}.uagb-social-share__wrapper{box-shadow:none}.uagb-social-share__outer-wrap:not(.uagb-social-share__no-label) .uagb-social-share__source-wrap{margin-right:15px}.uagb-social-share__outer-wrap.uagb-social-share__icon-at-top .uagb-social-share__source-wrap{-ms-flex-item-align:flex-start;align-self:flex-start;margin-top:5px}.uagb-block-4fccc0cd .uagb-ss-repeater span.uagb-ss__link{color: #3a3a3a;}.uagb-block-4fccc0cd .uagb-ss-repeater a.uagb-ss__link{color: #3a3a3a;}.uagb-block-4fccc0cd .uagb-ss-repeater span.uagb-ss__link svg{fill: #3a3a3a;}.uagb-block-4fccc0cd .uagb-ss-repeater a.uagb-ss__link svg{fill: #3a3a3a;}.uagb-block-4fccc0cd.uagb-social-share__layout-vertical .uagb-ss__wrapper{margin-left: 0;margin-right: 0;margin-top: 5px;margin-bottom: 5px;}.uagb-block-4fccc0cd.uagb-social-share__layout-vertical .uagb-ss__link{padding: 10px;}.uagb-block-4fccc0cd.uagb-social-share__layout-horizontal .uagb-ss__link{padding: 10px;}.uagb-block-4fccc0cd.uagb-social-share__layout-horizontal .uagb-ss__wrapper{margin-left: 5px;margin-right: 5px;}.uagb-block-4fccc0cd .wp-block-uagb-social-share-child {border-radius: 0px;}.uagb-block-4fccc0cd .uagb-ss__source-wrap{width: 30px;}.uagb-block-4fccc0cd .uagb-ss__source-wrap svg{width: 30px;height: 30px;}.uagb-block-4fccc0cd .uagb-ss__source-image{width: 30px;}.uagb-block-4fccc0cd .uagb-ss__source-icon{width: 30px;height: 30px;font-size: 30px;}.uagb-block-4fccc0cd.uagb-social-share__outer-wrap{justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: center;-ms-flex-align: center;align-items: center;}.uagb-block-c6bc91fb.uagb-ss-repeater span.uagb-ss__link{color: #3b5998;}.uagb-block-c6bc91fb.uagb-ss-repeater a.uagb-ss__link{color: #3b5998;}.uagb-block-c6bc91fb.uagb-ss-repeater span.uagb-ss__link svg{fill: #3b5998;}.uagb-block-c6bc91fb.uagb-ss-repeater a.uagb-ss__link svg{fill: #3b5998;}.uagb-block-7045e102.uagb-ss-repeater span.uagb-ss__link{color: #55acee;}.uagb-block-7045e102.uagb-ss-repeater a.uagb-ss__link{color: #55acee;}.uagb-block-7045e102.uagb-ss-repeater span.uagb-ss__link svg{fill: #55acee;}.uagb-block-7045e102.uagb-ss-repeater a.uagb-ss__link svg{fill: #55acee;}.uagb-block-1a7c39f8.uagb-ss-repeater span.uagb-ss__link{color: #bd081c;}.uagb-block-1a7c39f8.uagb-ss-repeater a.uagb-ss__link{color: #bd081c;}.uagb-block-1a7c39f8.uagb-ss-repeater span.uagb-ss__link svg{fill: #bd081c;}.uagb-block-1a7c39f8.uagb-ss-repeater a.uagb-ss__link svg{fill: #bd081c;}.uagb-block-ec5dba18.uagb-ss-repeater span.uagb-ss__link{color: #0077b5;}.uagb-block-ec5dba18.uagb-ss-repeater a.uagb-ss__link{color: #0077b5;}.uagb-block-ec5dba18.uagb-ss-repeater span.uagb-ss__link svg{fill: #0077b5;}.uagb-block-ec5dba18.uagb-ss-repeater a.uagb-ss__link svg{fill: #0077b5;}@media only screen and (max-width: 976px) {.uagb-block-4fccc0cd.uagb-social-share__layout-vertical .uagb-ss__wrapper{margin-left: 0;margin-right: 0;margin-top: 5px;margin-bottom: 5px;}.uagb-block-4fccc0cd.uagb-social-share__layout-horizontal .uagb-ss__wrapper{margin-left: 5px;margin-right: 5px;}.uagb-block-4fccc0cd.uagb-social-share__outer-wrap{justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: center;-ms-flex-align: center;align-items: center;}}@media only screen and (max-width: 767px) {.uagb-block-4fccc0cd.uagb-social-share__layout-vertical .uagb-ss__wrapper{margin-left: 0;margin-right: 0;margin-top: 5px;margin-bottom: 5px;}.uagb-block-4fccc0cd.uagb-social-share__layout-horizontal .uagb-ss__wrapper{margin-left: 5px;margin-right: 5px;}.uagb-block-4fccc0cd.uagb-social-share__outer-wrap{justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: center;-ms-flex-align: center;align-items: center;}}\ufeff.wp-block-uagb-table-of-contents .uagb-toc__wrap{display:inline-block;max-width:-moz-available;max-width:-webkit-fill-available;max-width:fill-available}.wp-block-uagb-table-of-contents li.uagb-toc__list{padding-top:10px}.wp-block-uagb-table-of-contents ul.uagb-toc__list,.wp-block-uagb-table-of-contents ol.uagb-toc__list{list-style-position:inside;padding-left:0;margin-bottom:0;margin-left:2.2em}.wp-block-uagb-table-of-contents ul.uagb-toc__list li,.wp-block-uagb-table-of-contents ol.uagb-toc__list li{margin:0}.wp-block-uagb-table-of-contents ul li:empty{display:none}.wp-block-uagb-table-of-contents .uagb-toc__title-wrap{display:flex;align-items:center}.wp-block-uagb-table-of-contents .uagb-toc__title{display:flex;align-items:center}.wp-block-uagb-table-of-contents .uagb-toc__is-collapsible.uagb-toc__title-wrap{cursor:pointer}.wp-block-uagb-table-of-contents .uag-toc__collapsible-wrap svg{width:20px;height:20px}.wp-block-uagb-table-of-contents svg{width:20px;height:20px;display:inline-block;margin-left:10px;cursor:pointer}.wp-block-uagb-table-of-contents .uag-toc__collapsible-wrap{display:flex;margin-left:10px;cursor:pointer}.wp-block-uagb-table-of-contents.uagb-toc__collapse .uagb-toc__list-wrap{display:none}.wp-block-uagb-table-of-contents.uagb-toc__collapse--list ul.uagb-toc__list,.wp-block-uagb-table-of-contents.uagb-toc__collapse--list ol.uagb-toc__list{padding-left:2px}ol.uagb-toc__list li.uagb-toc__list ul,ol.uagb-toc__list ul.uagb-toc__list ul{list-style-type:circle}ol.uagb-toc__list>ul,ol.uagb-toc__list>li{list-style-type:disc}.uagb-toc__scroll-top{position:fixed;right:50px;bottom:50px;display:none;padding:10px;background:#ccd0d4;cursor:pointer;font-size:1rem;line-height:1.8571428571}.uagb-toc__scroll-top svg{width:1.6em;height:.6em;margin-left:0;transform:translate(0, -20%) rotate(180deg);fill:currentColor}.uagb-toc__scroll-top.uagb-toc__show-scroll{display:inline-table}body[class*=astra] .uagb-toc__list{line-height:normal}.uagb-toc__list{margin-top:0}.wp-block-uagb-table-of-contents ol.uagb-toc__list li.uagb-toc__list.uagb-toc__list--expandable{list-style-type:none !important}ul.uagb-toc__list--child-of-closed-list{padding-top:0 !important}ul.uagb-toc__list--hidden-child{display:none !important}.list-open::before,.list-collapsed::before{content:\"\u25bc\"\/\"\";transition:transform .3s ease;transform:scale(0.7) translateX(-50%);display:inline-block}.list-collapsed::before{transform:scale(0.7) rotate(-90deg) translate(-84%, 6%)}span.list-open,span.list-collapsed{cursor:pointer;outline:none !important}.uagb-toc__list.transition{transition:max-height 300ms ease-in-out,padding-top 300ms ease-in-out}.uagb-toc__loader{border:2px solid #f3f3f3;border-top:2px solid #0073aa;border-radius:50%;width:20px;height:20px;animation:spin 1.1s linear infinite;display:block;position:absolute;margin-top:5px}.uagb-toc__list-hidden{opacity:0}@keyframes spin{0%{transform:rotate(0deg)}100%{transform:rotate(360deg)}}[dir=rtl] .list-open::before{transform:scale(0.7) translateX(50%)}[dir=rtl] .list-collapsed::before{transform:scale(0.7) rotate(90deg) translate(84%, 6%)}[dir=rtl] .wp-block-uagb-table-of-contents.uagb-toc__collapse--list ul.uagb-toc__list,[dir=rtl] .wp-block-uagb-table-of-contents.uagb-toc__collapse--list ol.uagb-toc__list{padding-left:0;padding-right:2px;margin-left:0;margin-right:2.2em}.uagb-block-fb1ed97f.wp-block-uagb-table-of-contents{text-align: left;}.uagb-block-fb1ed97f .uagb-toc__list-wrap li a{color: #54595F;}.uagb-block-fb1ed97f .uagb-toc__wrap .uagb-toc__title-wrap{justify-content: left;}.uagb-block-fb1ed97f .uagb-toc__wrap .uagb-toc__title{justify-content: left;}.uagb-block-fb1ed97f .uagb-toc__wrap{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-color: #333;border-style: solid;padding-left: 30px;padding-right: 30px;padding-top: 30px;padding-bottom: 30px;background: #fff;width: 100%;}.uagb-block-fb1ed97f .uagb-toc__list-wrap{column-count: 1;overflow: hidden;text-align: left;}.uagb-block-fb1ed97f .uagb-toc__list-wrap > ul.uagb-toc__list > li:first-child{padding-top: 0;}.uagb-block-fb1ed97f .uagb-toc__list-wrap ul.uagb-toc__list:last-child > li:last-child{padding-bottom: 0;}.uagb-block-fb1ed97f .uagb-toc__list .uagb-toc__list{list-style-type: disc !important;}.uagb-block-fb1ed97f .uagb-toc__title{font-weight: Default;font-size: 20px;}.uagb-block-fb1ed97f .uagb-toc__list-wrap ol li a{text-decoration: underline;}@media only screen and (max-width: 976px) {.uagb-block-fb1ed97f .uagb-toc__wrap{border-style: solid;}.uagb-block-fb1ed97f .uagb-toc__list-wrap{column-count: 1;overflow: hidden;text-align: left;}.uagb-block-fb1ed97f .uagb-toc__list-wrap > ul.uagb-toc__list > li:first-child{padding-top: 0;}.uagb-block-fb1ed97f .uagb-toc__list-wrap ul.uagb-toc__list:last-child > li:last-child{padding-bottom: 0;}}@media only screen and (max-width: 767px) {.uagb-block-fb1ed97f .uagb-toc__wrap{border-style: solid;}.uagb-block-fb1ed97f .uagb-toc__list-wrap{column-count: 1;overflow: hidden;text-align: left;}.uagb-block-fb1ed97f .uagb-toc__list-wrap > ul.uagb-toc__list > li:first-child{padding-top: 0;}.uagb-block-fb1ed97f .uagb-toc__list-wrap ul.uagb-toc__list:last-child > li:last-child{padding-bottom: 0;}}.wp-block-uagb-advanced-heading.uagb-block-7e58a885.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-7e58a885.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7e58a885.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7e58a885.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-439b004d.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-439b004d.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-439b004d.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-439b004d.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-b6d0fafa.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-b6d0fafa.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-b6d0fafa.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-b6d0fafa.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-315a5ade.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-315a5ade.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-315a5ade.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-315a5ade.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ba777024.wp-block-uagb-advanced-heading a{color: var(--ast-global-color-0);}.wp-block-uagb-advanced-heading.uagb-block-ba777024.wp-block-uagb-advanced-heading a:hover{color: var(--ast-global-color-3);}.wp-block-uagb-advanced-heading.uagb-block-ba777024.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-ba777024.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ba777024.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ba777024.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ba777024 .uagb-heading-text{font-size: 16px;}.wp-block-uagb-advanced-heading.uagb-block-fac50cea.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-fac50cea.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-fac50cea.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-fac50cea.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-d3dca839 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d3dca839 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d3dca839 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d3dca839 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d3dca839 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d3dca839{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d3dca839 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-d3dca839{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-8d41e658 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-8d41e658 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-8d41e658 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-8d41e658 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-8d41e658 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8d41e658{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8d41e658 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-8d41e658{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-f0e5048d.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-f0e5048d.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-f0e5048d.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f0e5048d.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f0e5048d.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-d00997b5 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d00997b5 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d00997b5 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d00997b5 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d00997b5 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d00997b5{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d00997b5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-d00997b5{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-c9d25173.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-c9d25173.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c9d25173.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c9d25173.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-ded34ed7 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ded34ed7 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ded34ed7 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ded34ed7 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ded34ed7 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ded34ed7{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ded34ed7 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-ded34ed7{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-40f360cd.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-40f360cd.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-40f360cd.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-40f360cd.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-b138ecc8 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b138ecc8 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b138ecc8 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b138ecc8 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b138ecc8 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b138ecc8{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b138ecc8 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-b138ecc8{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-35e63a50 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-35e63a50 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-35e63a50 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-35e63a50 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-35e63a50 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-35e63a50{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-35e63a50 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-35e63a50{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-d3dca839{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d3dca839 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-d3dca839{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8d41e658{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8d41e658 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-8d41e658{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d00997b5{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d00997b5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-d00997b5{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ded34ed7{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ded34ed7 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-ded34ed7{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b138ecc8{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b138ecc8 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-b138ecc8{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-35e63a50{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-35e63a50 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-35e63a50{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-d3dca839{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d3dca839 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-d3dca839{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8d41e658{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8d41e658 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-8d41e658{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d00997b5{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d00997b5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-d00997b5{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ded34ed7{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ded34ed7 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-ded34ed7{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b138ecc8{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b138ecc8 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-b138ecc8{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-35e63a50{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-35e63a50 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-35e63a50{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}}.wp-block-uagb-advanced-heading.uagb-block-80fe5339.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-80fe5339.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-80fe5339.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-80fe5339.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c1cae19f.wp-block-uagb-advanced-heading .uagb-heading-text{color: #0c1521;}.wp-block-uagb-advanced-heading.uagb-block-c1cae19f.wp-block-uagb-advanced-heading a{color: var(--ast-global-color-0);}.wp-block-uagb-advanced-heading.uagb-block-c1cae19f.wp-block-uagb-advanced-heading a:hover{color: var(--ast-global-color-3);}.wp-block-uagb-advanced-heading.uagb-block-c1cae19f.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-c1cae19f.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c1cae19f.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c1cae19f.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-47876513.wp-block-uagb-advanced-heading {margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-47876513.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-47876513.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-47876513.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-47876513.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-99c98669 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-99c98669 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-99c98669 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-99c98669 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-99c98669 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-99c98669{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-99c98669 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: wrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-99c98669{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-style: none;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-cb809d86 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-cb809d86 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-cb809d86 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-cb809d86 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-cb809d86 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-cb809d86{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-cb809d86 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-cb809d86{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-f7db15e5 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f7db15e5 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f7db15e5 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f7db15e5 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f7db15e5 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f7db15e5{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f7db15e5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-f7db15e5{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-0b48ab7e.wp-block-uagb-advanced-heading a{color: var(--ast-global-color-0);}.wp-block-uagb-advanced-heading.uagb-block-0b48ab7e.wp-block-uagb-advanced-heading a:hover{color: var(--ast-global-color-3);}.wp-block-uagb-advanced-heading.uagb-block-0b48ab7e.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-0b48ab7e.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0b48ab7e.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0b48ab7e.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-47f2ddc0 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-47f2ddc0 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-47f2ddc0 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-47f2ddc0 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-47f2ddc0 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-47f2ddc0{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-47f2ddc0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-47f2ddc0{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-99c98669{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-99c98669 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-99c98669{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;border-style: none;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-cb809d86{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-cb809d86 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-cb809d86{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f7db15e5{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f7db15e5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-f7db15e5{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-47f2ddc0{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-47f2ddc0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-47f2ddc0{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-99c98669{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-99c98669 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-99c98669{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;border-style: none;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-cb809d86{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-cb809d86 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-cb809d86{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f7db15e5{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f7db15e5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-f7db15e5{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-47f2ddc0{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-47f2ddc0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-47f2ddc0{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}}.wp-block-uagb-container.uagb-block-2f0903f2 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2f0903f2 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2f0903f2 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2f0903f2 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2f0903f2 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2f0903f2{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2f0903f2 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: wrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-2f0903f2{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-7947b83a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7947b83a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7947b83a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7947b83a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7947b83a .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7947b83a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7947b83a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-7947b83a{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-78c73a1a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-78c73a1a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-78c73a1a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-78c73a1a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-78c73a1a .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-78c73a1a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-78c73a1a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-78c73a1a{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-ec6cb9af.wp-block-uagb-advanced-heading a{color: var(--ast-global-color-0);}.wp-block-uagb-advanced-heading.uagb-block-ec6cb9af.wp-block-uagb-advanced-heading a:hover{color: var(--ast-global-color-3);}.wp-block-uagb-advanced-heading.uagb-block-ec6cb9af.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-ec6cb9af.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ec6cb9af.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ec6cb9af.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-c5420d67 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c5420d67 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c5420d67 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c5420d67 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c5420d67 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c5420d67{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c5420d67 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-c5420d67{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-2f0903f2{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2f0903f2 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-2f0903f2{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7947b83a{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7947b83a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-7947b83a{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-78c73a1a{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-78c73a1a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-78c73a1a{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c5420d67{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c5420d67 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-c5420d67{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-2f0903f2{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2f0903f2 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-2f0903f2{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7947b83a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7947b83a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-7947b83a{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-78c73a1a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-78c73a1a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-78c73a1a{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c5420d67{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c5420d67 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-c5420d67{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}}.wp-block-uagb-container.uagb-block-89cb8f77.wp-block-uagb-container{color: var(--ast-global-color-0);}.wp-block-uagb-container.uagb-block-89cb8f77.wp-block-uagb-container *{color: var(--ast-global-color-0);}.wp-block-uagb-container.uagb-block-89cb8f77 a{color: var(--ast-global-color-0);}.wp-block-uagb-container.uagb-block-89cb8f77 a:hover{color: var(--ast-global-color-1);}.wp-block-uagb-container.uagb-block-89cb8f77 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-89cb8f77 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-89cb8f77 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-89cb8f77 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-89cb8f77 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-89cb8f77{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-89cb8f77 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: wrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-89cb8f77{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-371371c0 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-371371c0 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-371371c0 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-371371c0 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-371371c0 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-371371c0{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-371371c0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-371371c0{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-de625655 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-de625655 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-de625655 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-de625655 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-de625655 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-de625655{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-de625655 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-de625655{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-067f80c2.wp-block-uagb-advanced-heading a{color: var(--ast-global-color-0);}.wp-block-uagb-advanced-heading.uagb-block-067f80c2.wp-block-uagb-advanced-heading a:hover{color: var(--ast-global-color-3);}.wp-block-uagb-advanced-heading.uagb-block-067f80c2.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-067f80c2.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-067f80c2.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-067f80c2.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-607ce38d .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-607ce38d .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-607ce38d .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-607ce38d .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-607ce38d .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-607ce38d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-607ce38d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-607ce38d{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-89cb8f77{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-89cb8f77 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-89cb8f77{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-371371c0{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-371371c0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-371371c0{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-de625655{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-de625655 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-de625655{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-607ce38d{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-607ce38d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-607ce38d{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-89cb8f77{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-89cb8f77 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-89cb8f77{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-371371c0{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-371371c0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-371371c0{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-de625655{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-de625655 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-de625655{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-607ce38d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-607ce38d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-607ce38d{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}}.wp-block-uagb-container.uagb-block-3e682cc4 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3e682cc4 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3e682cc4 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3e682cc4 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3e682cc4 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3e682cc4{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3e682cc4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-3e682cc4{box-shadow: 0px 0px   #00000070 ;padding-top: 0%;padding-bottom: 0%;padding-left: 0%;padding-right: 20%;margin-top: 0% !important;margin-bottom: 0% !important;margin-left: 0%;margin-right: 0%;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-3e682cc4{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3e682cc4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-3e682cc4{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 20px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-3e682cc4{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3e682cc4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-3e682cc4{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 20px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}}\";s:2:\"js\";s:1794:\"document.addEventListener(\"DOMContentLoaded\", function(){ window.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-405f2303' );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-1377f6f5' );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-bca1faf8' );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-18dfdf02' );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-f6b2cf64' );\n});\nvar ssLinksParent = document.querySelector( '.uagb-block-4fccc0cd' );\nssLinksParent?.addEventListener( 'keyup', function ( e ) {\nvar link = e.target.closest( '.uagb-ss__link' );\nif ( link && e.keyCode === 13 ) {\n\thandleSocialLinkClick( link );\n}\n});\n\nssLinksParent?.addEventListener( 'click', function ( e ) {\nvar link = e.target.closest( '.uagb-ss__link' );\nif ( link ) {\n\thandleSocialLinkClick( link );\n}\n});\n\nfunction handleSocialLinkClick( link ) {\nvar social_url = link.dataset.href;\nvar target = \"\";\nif ( social_url == \"mailto:?body=\" ) {\n\ttarget = \"_self\";\n}\nvar request_url = \"\";\nif ( social_url.indexOf(\"\/pin\/create\/link\/?url=\") !== -1 ) {\n\trequest_url = social_url + encodeURIComponent( window.location.href ) + \"&media=\" + 'https:\/\/epayspace.com\/wp-content\/uploads\/2024\/02\/1x11.png';\n} else {\n\trequest_url = social_url + encodeURIComponent( window.location.href );\n}\nwindow.open( request_url, target );\n}\nwindow.addEventListener( 'load', function(){\n\tUAGBTableOfContents._run( {\"mappingHeaders\":[true,true,true,true,true,true],\"scrollToTop\":false,\"makeCollapsible\":false,\"enableCollapsableList\":false,\"initialCollapse\":false,\"markerView\":\"disc\",\"isFrontend\":true,\"initiallyCollapseList\":false}, '.uagb-block-fb1ed97f' );\n} );\n });\";s:18:\"current_block_list\";a:23:{i:0;s:14:\"uagb\/container\";i:1;s:21:\"uagb\/advanced-heading\";i:3;s:12:\"core\/heading\";i:4;s:14:\"core\/paragraph\";i:5;s:12:\"uagb\/buttons\";i:6;s:18:\"uagb\/buttons-child\";i:8;s:10:\"core\/image\";i:9;s:11:\"core\/search\";i:10;s:10:\"core\/group\";i:11;s:17:\"core\/latest-posts\";i:12;s:20:\"core\/latest-comments\";i:13;s:13:\"core\/archives\";i:14;s:15:\"core\/categories\";i:15;s:12:\"core\/columns\";i:16;s:11:\"core\/column\";i:18;s:9:\"core\/list\";i:19;s:14:\"core\/list-item\";i:20;s:17:\"core\/widget-group\";i:21;s:17:\"uagb\/social-share\";i:22;s:23:\"uagb\/social-share-child\";i:23;s:22:\"uagb\/table-of-contents\";i:25;s:22:\"wpml\/language-switcher\";i:26;s:12:\"core\/gallery\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1778692286\";s:6:\"gfonts\";a:2:{s:9:\"Maven Pro\";a:2:{s:10:\"fontfamily\";s:9:\"Maven Pro\";s:12:\"fontvariants\";a:1:{i:0;s:3:\"700\";}}s:6:\"Roboto\";a:2:{s:10:\"fontfamily\";s:6:\"Roboto\";s:12:\"fontvariants\";a:1:{i:0;s:3:\"700\";}}}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/epayspace.com\/wp-content\/uploads\/2024\/02\/1x11.png",377,238,false],"thumbnail":["https:\/\/epayspace.com\/wp-content\/uploads\/2024\/02\/1x11-150x150.png",150,150,true],"medium":["https:\/\/epayspace.com\/wp-content\/uploads\/2024\/02\/1x11-300x189.png",300,189,true],"medium_large":["https:\/\/epayspace.com\/wp-content\/uploads\/2024\/02\/1x11.png",377,238,false],"large":["https:\/\/epayspace.com\/wp-content\/uploads\/2024\/02\/1x11.png",377,238,false],"1536x1536":["https:\/\/epayspace.com\/wp-content\/uploads\/2024\/02\/1x11.png",377,238,false],"2048x2048":["https:\/\/epayspace.com\/wp-content\/uploads\/2024\/02\/1x11.png",377,238,false]},"uagb_author_info":{"display_name":"Alexandre Baranger","author_link":"https:\/\/epayspace.com\/fr\/author\/a-baranger\/"},"uagb_comment_info":0,"uagb_excerpt":"L'open banking ou syst\u00e8me bancaire ouvert ? Evolution ou ouverture \u00e0 de nouveaux risques ? D\u00e9couvrez le dans notre blog d\u00e9di\u00e9.","_links":{"self":[{"href":"https:\/\/epayspace.com\/fr\/wp-json\/wp\/v2\/posts\/2428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/epayspace.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/epayspace.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/epayspace.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/epayspace.com\/fr\/wp-json\/wp\/v2\/comments?post=2428"}],"version-history":[{"count":15,"href":"https:\/\/epayspace.com\/fr\/wp-json\/wp\/v2\/posts\/2428\/revisions"}],"predecessor-version":[{"id":4726,"href":"https:\/\/epayspace.com\/fr\/wp-json\/wp\/v2\/posts\/2428\/revisions\/4726"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/epayspace.com\/fr\/wp-json\/wp\/v2\/media\/4152"}],"wp:attachment":[{"href":"https:\/\/epayspace.com\/fr\/wp-json\/wp\/v2\/media?parent=2428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/epayspace.com\/fr\/wp-json\/wp\/v2\/categories?post=2428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/epayspace.com\/fr\/wp-json\/wp\/v2\/tags?post=2428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}